{"id":745,"date":"2015-12-15T09:18:05","date_gmt":"2015-12-15T08:18:05","guid":{"rendered":"http:\/\/www.drinkatering.com\/?p=688"},"modified":"2025-01-23T22:52:10","modified_gmt":"2025-01-23T21:52:10","slug":"dicho-y-hecho-aqui-esta-la-casa-del-agua-en-castano-primo","status":"publish","type":"post","link":"https:\/\/drinkatering.com\/es\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/","title":{"rendered":"Dicho y hecho: Casa del Agua Castano Primo"},"content":{"rendered":"<p>El pueblo de Castano llevaba meses esperando este acontecimiento, y por fin,\u00a0<strong>Martes 15 de diciembre a las 11.00 horas en la Piazza Ardizzone<\/strong>Se inaugura la Casa del Agua.<br \/>\nLa cinta se cort\u00f3 en presencia del\u00a0<strong>El Presidente del Grupo CAP, Alessandro Russo, y el Alcalde, Giuseppe Pignatiello<\/strong>\u00a0y b<strong>ni\u00f1os de primaria<\/strong>\u00a0del municipio que dieron la bienvenida a la Casita agitando banderas azules y blancas con el lema \"tu agua en buenas manos\". L'<strong>agua de kil\u00f3metro cero suministrada por la planta es, de hecho, excelente, segura y controlada<\/strong>\u00a0las normas de calidad m\u00e1s estrictas que garantizan la seguridad alimentaria.<\/p>","protected":false},"excerpt":{"rendered":"<p>Da mesi i castanesi stavano attendendo questo evento e finalmente,\u00a0Marted\u00ec 15 Dicembre alle ore 11:00 in Piazza Ardizzone, \u00e8 stata inaugurata la Casa dell\u2019Acqua. Il nastro \u00e8 stato tagliato alla presenza del\u00a0Presidente del Gruppo CAP Alessandro Russo, del Sindaco Giuseppe Pignatiello\u00a0e dei bambini delle scuole primarie\u00a0del Comune che hanno dato il benvenuto alla Casetta sventolando [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary dkr-read-more-link\" href=\"https:\/\/drinkatering.com\/es\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/\">Leer m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"author":10,"featured_media":1378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71],"tags":[],"class_list":["post-745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuove-inagurazioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Detto e fatto: ecco la Casa dell\u2019Acqua di Castano Primo - DKR<\/title>\n<meta name=\"description\" content=\"Castano Primo inaugura la sua Casa dell\u2019Acqua DKR! Acqua fresca, sostenibile ed economica per tutti i cittadini.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drinkatering.com\/es\/dicho-y-hecho-aqui-esta-la-casa-del-agua-en-castano-primo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detto e fatto: ecco la Casa dell\u2019Acqua di Castano Primo - DKR\" \/>\n<meta property=\"og:description\" content=\"Castano Primo inaugura la sua Casa dell\u2019Acqua DKR! Acqua fresca, sostenibile ed economica per tutti i cittadini.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drinkatering.com\/es\/dicho-y-hecho-aqui-esta-la-casa-del-agua-en-castano-primo\/\" \/>\n<meta property=\"og:site_name\" content=\"DKR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dkrdrinkatering\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-15T08:18:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T21:52:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/12\/casa-dellacqua-castano-primo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"433\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alberto Rudoni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto Rudoni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/\"},\"author\":{\"name\":\"Alberto Rudoni\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#\\\/schema\\\/person\\\/7819fad04bb01cda4cf9e766056c66d6\"},\"headline\":\"Detto e fatto: ecco la Casa dell\u2019Acqua di Castano Primo\",\"datePublished\":\"2015-12-15T08:18:05+00:00\",\"dateModified\":\"2025-01-23T21:52:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/\"},\"wordCount\":105,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/casa-dellacqua-castano-primo.jpg\",\"articleSection\":[\"Nuove Inagurazioni\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/\",\"name\":\"Detto e fatto: ecco la Casa dell\u2019Acqua di Castano Primo - DKR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/casa-dellacqua-castano-primo.jpg\",\"datePublished\":\"2015-12-15T08:18:05+00:00\",\"dateModified\":\"2025-01-23T21:52:10+00:00\",\"description\":\"Castano Primo inaugura la sua Casa dell\u2019Acqua DKR! Acqua fresca, sostenibile ed economica per tutti i cittadini.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/casa-dellacqua-castano-primo.jpg\",\"contentUrl\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/casa-dellacqua-castano-primo.jpg\",\"width\":433,\"height\":243,\"caption\":\"Da mesi i castanesi stavano attendendo questo evento e finalmente \u00e8 stata inaugurata la nuova casa dell'acqua di Castano Primo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/drinkatering.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detto e fatto: ecco la Casa dell\u2019Acqua di Castano Primo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#website\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/\",\"name\":\"drinkatering\",\"description\":\"Case dell&#039;Acqua e Apparecchiature per Erogazione Bevande\",\"publisher\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drinkatering.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#organization\",\"name\":\"drinkatering\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.png\",\"width\":168,\"height\":74,\"caption\":\"drinkatering\"},\"image\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dkrdrinkatering\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dkr-drinkatering\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#\\\/schema\\\/person\\\/7819fad04bb01cda4cf9e766056c66d6\",\"name\":\"Alberto Rudoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g\",\"caption\":\"Alberto Rudoni\"},\"url\":\"https:\\\/\\\/drinkatering.com\\\/es\\\/author\\\/redapple\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dicho y hecho: la Casa del Agua Castano Primo - DKR","description":"\u00a1Castano Primo inaugura su Casa del Agua DKR! Agua fresca, sostenible y asequible para todos los ciudadanos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drinkatering.com\/es\/dicho-y-hecho-aqui-esta-la-casa-del-agua-en-castano-primo\/","og_locale":"es_ES","og_type":"article","og_title":"Detto e fatto: ecco la Casa dell\u2019Acqua di Castano Primo - DKR","og_description":"Castano Primo inaugura la sua Casa dell\u2019Acqua DKR! Acqua fresca, sostenibile ed economica per tutti i cittadini.","og_url":"https:\/\/drinkatering.com\/es\/dicho-y-hecho-aqui-esta-la-casa-del-agua-en-castano-primo\/","og_site_name":"DKR","article_publisher":"https:\/\/www.facebook.com\/dkrdrinkatering","article_published_time":"2015-12-15T08:18:05+00:00","article_modified_time":"2025-01-23T21:52:10+00:00","og_image":[{"width":433,"height":243,"url":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/12\/casa-dellacqua-castano-primo.jpg","type":"image\/jpeg"}],"author":"Alberto Rudoni","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alberto Rudoni","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/#article","isPartOf":{"@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/"},"author":{"name":"Alberto Rudoni","@id":"https:\/\/drinkatering.com\/#\/schema\/person\/7819fad04bb01cda4cf9e766056c66d6"},"headline":"Detto e fatto: ecco la Casa dell\u2019Acqua di Castano Primo","datePublished":"2015-12-15T08:18:05+00:00","dateModified":"2025-01-23T21:52:10+00:00","mainEntityOfPage":{"@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/"},"wordCount":105,"commentCount":0,"publisher":{"@id":"https:\/\/drinkatering.com\/#organization"},"image":{"@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/#primaryimage"},"thumbnailUrl":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/12\/casa-dellacqua-castano-primo.jpg","articleSection":["Nuove Inagurazioni"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/","url":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/","name":"Dicho y hecho: la Casa del Agua Castano Primo - DKR","isPartOf":{"@id":"https:\/\/drinkatering.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/#primaryimage"},"image":{"@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/#primaryimage"},"thumbnailUrl":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/12\/casa-dellacqua-castano-primo.jpg","datePublished":"2015-12-15T08:18:05+00:00","dateModified":"2025-01-23T21:52:10+00:00","description":"\u00a1Castano Primo inaugura su Casa del Agua DKR! Agua fresca, sostenible y asequible para todos los ciudadanos.","breadcrumb":{"@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/#primaryimage","url":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/12\/casa-dellacqua-castano-primo.jpg","contentUrl":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/12\/casa-dellacqua-castano-primo.jpg","width":433,"height":243,"caption":"Da mesi i castanesi stavano attendendo questo evento e finalmente \u00e8 stata inaugurata la nuova casa dell'acqua di Castano Primo"},{"@type":"BreadcrumbList","@id":"https:\/\/drinkatering.com\/detto-e-fatto-ecco-la-casa-dellacqua-di-castano-primo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drinkatering.com\/"},{"@type":"ListItem","position":2,"name":"Detto e fatto: ecco la Casa dell\u2019Acqua di Castano Primo"}]},{"@type":"WebSite","@id":"https:\/\/drinkatering.com\/#website","url":"https:\/\/drinkatering.com\/","name":"bebiendo","description":"Casas de agua y equipos dispensadores de bebidas","publisher":{"@id":"https:\/\/drinkatering.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drinkatering.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/drinkatering.com\/#organization","name":"bebiendo","url":"https:\/\/drinkatering.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/drinkatering.com\/#\/schema\/logo\/image\/","url":"https:\/\/drinkatering.com\/wp-content\/uploads\/2022\/01\/logo.png","contentUrl":"https:\/\/drinkatering.com\/wp-content\/uploads\/2022\/01\/logo.png","width":168,"height":74,"caption":"drinkatering"},"image":{"@id":"https:\/\/drinkatering.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dkrdrinkatering","https:\/\/www.linkedin.com\/company\/dkr-drinkatering\/"]},{"@type":"Person","@id":"https:\/\/drinkatering.com\/#\/schema\/person\/7819fad04bb01cda4cf9e766056c66d6","name":"Alberto Rudoni","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g","caption":"Alberto Rudoni"},"url":"https:\/\/drinkatering.com\/es\/author\/redapple\/"}]}},"_links":{"self":[{"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/posts\/745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/comments?post=745"}],"version-history":[{"count":0,"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/posts\/745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/media\/1378"}],"wp:attachment":[{"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/media?parent=745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/categories?post=745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drinkatering.com\/es\/wp-json\/wp\/v2\/tags?post=745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}