{"id":753,"date":"2015-03-22T09:33:02","date_gmt":"2015-03-22T08:33:02","guid":{"rendered":"http:\/\/www.drinkatering.com\/?p=712"},"modified":"2025-01-23T22:33:54","modified_gmt":"2025-01-23T21:33:54","slug":"cassina-de-pecchi-here-is-the-new-water-house","status":"publish","type":"post","link":"https:\/\/drinkatering.com\/en\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/","title":{"rendered":"Cassina De Pecchi: the new Water House"},"content":{"rendered":"<p><em>\"I am the river water flowing between the stone banks, between the white trees whispering in the evening wind through willow forests.<br \/>\nI am the river water and I run as far as time runs infinitely.<\/em><br \/>\n<em><strong>I am Life.<\/strong>\"<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>During the\u00a0<strong>World Water Day 2015<\/strong>On Sunday 22 March at 16:00 in Piazza Decorati al Valore Civile, the\u00a0<strong>Cassina De' Pecchi Water House<\/strong>.<\/p>\n<p>\"<em>A day for water, water for sustainable development<\/em>\". This is the motto of the\u00a0<strong>Water Day 2015<\/strong>\u00a0and it is also the principle by which the\u00a0<strong>Dkr Water Houses<\/strong>, \"<em>Friends of the Environment<\/em>\" as they reduce, not only the use of plastic by reusing glass containers, but also the CO2 emissions for the transport and production of PET.<\/p>\n<p>Despite the rainy day, the citizens participated with great enthusiasm, as water is a particularly important topic in Cassina De' Pecchi,\u00a0<strong>fourth grade children even became the 'designers' of a campaign to promote the conscious use of water, in collaboration with Poste Italiane Spa.<\/strong><\/p>\n<p><strong><em>Let us preserve this important resource, Water is 'of and for all'.<\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cIo sono l\u2019acqua di fiume che scorre tra le rive di pietra, tra gli alberi bianchi che sussurrano al vento della sera tra boschi di salici. Io sono l\u2019acqua di fiume e corro lontano, come corre infinito il tempo. Io sono la Vita.\u201d &nbsp; Durante la\u00a0Giornata Mondiale dell\u2019Acqua 2015, Domenica 22 Marzo alle ore 16:00 [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary dkr-read-more-link\" href=\"https:\/\/drinkatering.com\/en\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":10,"featured_media":1390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71],"tags":[],"class_list":["post-753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuove-inagurazioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cassina De Pecchi: ecco la nuova Casa dell&#039;Acqua - DKR<\/title>\n<meta name=\"description\" content=\"Cassina de\u2019 Pecchi accoglie una nuova Casa dell\u2019Acqua DKR: risparmio, sostenibilit\u00e0 e acqua fresca per tutti!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drinkatering.com\/en\/cassina-de-pecchi-here-is-the-new-water-house\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassina De Pecchi: ecco la nuova Casa dell&#039;Acqua - DKR\" \/>\n<meta property=\"og:description\" content=\"Cassina de\u2019 Pecchi accoglie una nuova Casa dell\u2019Acqua DKR: risparmio, sostenibilit\u00e0 e acqua fresca per tutti!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drinkatering.com\/en\/cassina-de-pecchi-here-is-the-new-water-house\/\" \/>\n<meta property=\"og:site_name\" content=\"DKR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dkrdrinkatering\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-22T08:33:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T21:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/03\/casa-dellacqua-cassina-de-pecchi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"433\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alberto Rudoni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto Rudoni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/\"},\"author\":{\"name\":\"Alberto Rudoni\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#\\\/schema\\\/person\\\/7819fad04bb01cda4cf9e766056c66d6\"},\"headline\":\"Cassina De Pecchi: ecco la nuova Casa dell&#8217;Acqua\",\"datePublished\":\"2015-03-22T08:33:02+00:00\",\"dateModified\":\"2025-01-23T21:33:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/\"},\"wordCount\":203,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/casa-dellacqua-cassina-de-pecchi.jpg\",\"articleSection\":[\"Nuove Inagurazioni\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/\",\"name\":\"Cassina De Pecchi: ecco la nuova Casa dell'Acqua - DKR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/casa-dellacqua-cassina-de-pecchi.jpg\",\"datePublished\":\"2015-03-22T08:33:02+00:00\",\"dateModified\":\"2025-01-23T21:33:54+00:00\",\"description\":\"Cassina de\u2019 Pecchi accoglie una nuova Casa dell\u2019Acqua DKR: risparmio, sostenibilit\u00e0 e acqua fresca per tutti!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/casa-dellacqua-cassina-de-pecchi.jpg\",\"contentUrl\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/casa-dellacqua-cassina-de-pecchi.jpg\",\"width\":433,\"height\":243,\"caption\":\"Durante la\u00a0Giornata Mondiale dell\u2019Acqua, in Piazza Decorati al Valore Civile, \u00e8 stata inaugurata la Casa dell\u2019Acqua di Cassina De\u2019 Pecchi. Prodotto da Drinkatering\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/drinkatering.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassina De Pecchi: ecco la nuova Casa dell&#8217;Acqua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#website\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/\",\"name\":\"drinkatering\",\"description\":\"Case dell&#039;Acqua e Apparecchiature per Erogazione Bevande\",\"publisher\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drinkatering.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#organization\",\"name\":\"drinkatering\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/drinkatering.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.png\",\"width\":168,\"height\":74,\"caption\":\"drinkatering\"},\"image\":{\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dkrdrinkatering\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dkr-drinkatering\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/drinkatering.com\\\/#\\\/schema\\\/person\\\/7819fad04bb01cda4cf9e766056c66d6\",\"name\":\"Alberto Rudoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g\",\"caption\":\"Alberto Rudoni\"},\"url\":\"https:\\\/\\\/drinkatering.com\\\/en\\\/author\\\/redapple\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cassina De Pecchi: the new Water House - DKR","description":"Cassina de' Pecchi welcomes a new DKR Water House: savings, sustainability and fresh water for all!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drinkatering.com\/en\/cassina-de-pecchi-here-is-the-new-water-house\/","og_locale":"en_GB","og_type":"article","og_title":"Cassina De Pecchi: ecco la nuova Casa dell'Acqua - DKR","og_description":"Cassina de\u2019 Pecchi accoglie una nuova Casa dell\u2019Acqua DKR: risparmio, sostenibilit\u00e0 e acqua fresca per tutti!","og_url":"https:\/\/drinkatering.com\/en\/cassina-de-pecchi-here-is-the-new-water-house\/","og_site_name":"DKR","article_publisher":"https:\/\/www.facebook.com\/dkrdrinkatering","article_published_time":"2015-03-22T08:33:02+00:00","article_modified_time":"2025-01-23T21:33:54+00:00","og_image":[{"width":433,"height":243,"url":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/03\/casa-dellacqua-cassina-de-pecchi.jpg","type":"image\/jpeg"}],"author":"Alberto Rudoni","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alberto Rudoni","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/#article","isPartOf":{"@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/"},"author":{"name":"Alberto Rudoni","@id":"https:\/\/drinkatering.com\/#\/schema\/person\/7819fad04bb01cda4cf9e766056c66d6"},"headline":"Cassina De Pecchi: ecco la nuova Casa dell&#8217;Acqua","datePublished":"2015-03-22T08:33:02+00:00","dateModified":"2025-01-23T21:33:54+00:00","mainEntityOfPage":{"@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/"},"wordCount":203,"commentCount":0,"publisher":{"@id":"https:\/\/drinkatering.com\/#organization"},"image":{"@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/#primaryimage"},"thumbnailUrl":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/03\/casa-dellacqua-cassina-de-pecchi.jpg","articleSection":["Nuove Inagurazioni"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/","url":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/","name":"Cassina De Pecchi: the new Water House - DKR","isPartOf":{"@id":"https:\/\/drinkatering.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/#primaryimage"},"image":{"@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/#primaryimage"},"thumbnailUrl":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/03\/casa-dellacqua-cassina-de-pecchi.jpg","datePublished":"2015-03-22T08:33:02+00:00","dateModified":"2025-01-23T21:33:54+00:00","description":"Cassina de' Pecchi welcomes a new DKR Water House: savings, sustainability and fresh water for all!","breadcrumb":{"@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/#primaryimage","url":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/03\/casa-dellacqua-cassina-de-pecchi.jpg","contentUrl":"https:\/\/drinkatering.com\/wp-content\/uploads\/2015\/03\/casa-dellacqua-cassina-de-pecchi.jpg","width":433,"height":243,"caption":"Durante la\u00a0Giornata Mondiale dell\u2019Acqua, in Piazza Decorati al Valore Civile, \u00e8 stata inaugurata la Casa dell\u2019Acqua di Cassina De\u2019 Pecchi. Prodotto da Drinkatering"},{"@type":"BreadcrumbList","@id":"https:\/\/drinkatering.com\/cassina-de-pecchi-ecco-la-nuova-casa-dellacqua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drinkatering.com\/"},{"@type":"ListItem","position":2,"name":"Cassina De Pecchi: ecco la nuova Casa dell&#8217;Acqua"}]},{"@type":"WebSite","@id":"https:\/\/drinkatering.com\/#website","url":"https:\/\/drinkatering.com\/","name":"drinkatering","description":"Public Fountains and Beverage Dispensing Equipment","publisher":{"@id":"https:\/\/drinkatering.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drinkatering.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/drinkatering.com\/#organization","name":"drinkatering","url":"https:\/\/drinkatering.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/drinkatering.com\/#\/schema\/logo\/image\/","url":"https:\/\/drinkatering.com\/wp-content\/uploads\/2022\/01\/logo.png","contentUrl":"https:\/\/drinkatering.com\/wp-content\/uploads\/2022\/01\/logo.png","width":168,"height":74,"caption":"drinkatering"},"image":{"@id":"https:\/\/drinkatering.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dkrdrinkatering","https:\/\/www.linkedin.com\/company\/dkr-drinkatering\/"]},{"@type":"Person","@id":"https:\/\/drinkatering.com\/#\/schema\/person\/7819fad04bb01cda4cf9e766056c66d6","name":"Alberto Rudoni","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1511faaaa29480384f7cc1753d1116b4b059cfcd36fa9c1a1a01cdfcdc5046c2?s=96&d=mm&r=g","caption":"Alberto Rudoni"},"url":"https:\/\/drinkatering.com\/en\/author\/redapple\/"}]}},"_links":{"self":[{"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/posts\/753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/comments?post=753"}],"version-history":[{"count":0,"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/posts\/753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/media\/1390"}],"wp:attachment":[{"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/media?parent=753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/categories?post=753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drinkatering.com\/en\/wp-json\/wp\/v2\/tags?post=753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}